{"id":265,"date":"2022-01-09T16:02:52","date_gmt":"2022-01-09T16:02:52","guid":{"rendered":"https:\/\/dev.euroports.fi\/?page_id=265"},"modified":"2025-03-29T15:01:16","modified_gmt":"2025-03-29T12:01:16","slug":"varustamopalvelut","status":"publish","type":"page","link":"https:\/\/euroports.staging.bojaco.com\/en\/varustamopalvelut\/","title":{"rendered":"Ships' agency services"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"265\" class=\"elementor elementor-265\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15f0818f e-flex e-con-boxed e-con e-parent\" data-id=\"15f0818f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66b1b040 elementor-widget elementor-widget-image\" data-id=\"66b1b040\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/euroports.staging.bojaco.com\/wp-content\/uploads\/2022\/01\/EUROPORTS_finland_Satama_maailmalla.jpg\" title=\"\" alt=\"Laiva\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e758a90 e-flex e-con-boxed e-con e-parent\" data-id=\"4e758a90\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-569ec917 e-con-full e-flex e-con e-child\" data-id=\"569ec917\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-633a7400 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"633a7400\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5976db45 elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"5976db45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ships' agency services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e04e25 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"5e04e25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ships' agency<br>SERVICES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-103b5967 e-con-full e-flex e-con e-child\" data-id=\"103b5967\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-295217e elementor-widget elementor-widget-text-editor\" data-id=\"295217e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ships\u2019 agency services are provided round the clock with 24\/7 availability of our ship-owners\u2019 agents. We represent more than 40 different shipping companies and provide ship-owners\u2019 services to more than one thousand vessels every year.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6813af07 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6813af07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-6813af07{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64b127d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"64b127d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/euroports.staging.bojaco.com\/en\/palvelut\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M480 256A224 224 0 1 1 32 256a224 224 0 1 1 448 0zM0 256a256 256 0 1 0 512 0A256 256 0 1 0 0 256zM299.3 363.3l96-96c6.2-6.2 6.2-16.4 0-22.6l-96-96c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6L345.4 240 144 240c-8.8 0-16 7.2-16 16s7.2 16 16 16l201.4 0-68.7 68.7c-6.2 6.2-6.2 16.4 0 22.6s16.4 6.2 22.6 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Our services<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/euroports.staging.bojaco.com\/wp-content\/uploads\/2024\/12\/ContainerTerminalServices_2025_ENG.pdf\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M480 256A224 224 0 1 1 32 256a224 224 0 1 1 448 0zM0 256a256 256 0 1 0 512 0A256 256 0 1 0 0 256zM299.3 363.3l96-96c6.2-6.2 6.2-16.4 0-22.6l-96-96c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6L345.4 240 144 240c-8.8 0-16 7.2-16 16s7.2 16 16 16l201.4 0-68.7 68.7c-6.2 6.2-6.2 16.4 0 22.6s16.4 6.2 22.6 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Price list<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/euroports.staging.bojaco.com\/en\/yhteystietomme\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M480 256A224 224 0 1 1 32 256a224 224 0 1 1 448 0zM0 256a256 256 0 1 0 512 0A256 256 0 1 0 0 256zM299.3 363.3l96-96c6.2-6.2 6.2-16.4 0-22.6l-96-96c-6.2-6.2-16.4-6.2-22.6 0s-6.2 16.4 0 22.6L345.4 240 144 240c-8.8 0-16 7.2-16 16s7.2 16 16 16l201.4 0-68.7 68.7c-6.2 6.2-6.2 16.4 0 22.6s16.4 6.2 22.6 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Contact us<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-593ef411 overflow-hidden e-flex e-con-boxed e-con e-parent\" data-id=\"593ef411\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-25c58ce7 e-con-full e-flex e-con e-child\" data-id=\"25c58ce7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57f91c8 elementor-widget elementor-widget-spacer\" data-id=\"57f91c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c49f393 elementor-widget elementor-widget-heading\" data-id=\"4c49f393\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">At your service 24\/7<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76043104 elementor-widget elementor-widget-text-editor\" data-id=\"76043104\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our ship agents are at your service 24\/7. Our operations are based on our customers' needs. We take care of all the communication related to vessel calls: ordering the pilot, reserving the berth, customs clearance, and cargo documentation.<\/p><p>Our extensive experience in liner and other shipping operations enables us to offer high-quality and cost-effective services.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec115e8 overflow-hidden e-flex e-con-boxed e-con e-parent\" data-id=\"ec115e8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c08caaf e-con-full e-flex e-con e-child\" data-id=\"c08caaf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6ff4e48 e-grid e-con-full e-con e-child\" data-id=\"6ff4e48\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1b29036 e-con-full e-flex e-con e-child\" data-id=\"1b29036\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08c9511 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"08c9511\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-clock\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256,8C119,8,8,119,8,256S119,504,256,504,504,393,504,256,393,8,256,8Zm92.49,313h0l-20,25a16,16,0,0,1-22.49,2.5h0l-67-49.72a40,40,0,0,1-15-31.23V112a16,16,0,0,1,16-16h32a16,16,0,0,1,16,16V256l58,42.5A16,16,0,0,1,348.49,321Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85054a0 elementor-widget elementor-widget-heading\" data-id=\"85054a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fast and efficient vessel calls<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0fa2370 e-con-full e-flex e-con e-child\" data-id=\"0fa2370\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34ee137 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"34ee137\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-dharmachakra\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74698e9 elementor-widget elementor-widget-heading\" data-id=\"74698e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Crew and vessel support services<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b924ba e-con-full e-flex e-con e-child\" data-id=\"8b924ba\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57fa404 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"57fa404\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ship\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496.616 372.639l70.012-70.012c16.899-16.9 9.942-45.771-12.836-53.092L512 236.102V96c0-17.673-14.327-32-32-32h-64V24c0-13.255-10.745-24-24-24H248c-13.255 0-24 10.745-24 24v40h-64c-17.673 0-32 14.327-32 32v140.102l-41.792 13.433c-22.753 7.313-29.754 36.173-12.836 53.092l70.012 70.012C125.828 416.287 85.587 448 24 448c-13.255 0-24 10.745-24 24v16c0 13.255 10.745 24 24 24 61.023 0 107.499-20.61 143.258-59.396C181.677 487.432 216.021 512 256 512h128c39.979 0 74.323-24.568 88.742-59.396C508.495 491.384 554.968 512 616 512c13.255 0 24-10.745 24-24v-16c0-13.255-10.745-24-24-24-60.817 0-101.542-31.001-119.384-75.361zM192 128h256v87.531l-118.208-37.995a31.995 31.995 0 0 0-19.584 0L192 215.531V128z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0afa7e8 elementor-widget elementor-widget-heading\" data-id=\"0afa7e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Documentation and regulatory compliance<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c770b0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c770b0b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-9b0dde5\" data-id=\"9b0dde5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-351e0ed elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"351e0ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b099fc3 elementor-widget elementor-widget-heading\" data-id=\"b099fc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-89f4ba1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"89f4ba1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-342c501\" data-id=\"342c501\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2f3c69 elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"f2f3c69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">send us a<br>message<\/h3><p class=\"elementor-image-box-description\">Do you have a question or wish to give us some feedback? You can send us a message by filling in the contact form on our website.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddcf003 elementor-widget elementor-widget-spacer\" data-id=\"ddcf003\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f0976c elementor-widget elementor-widget-button\" data-id=\"4f0976c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/euroports.staging.bojaco.com\/en\/ota-yhteytta\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact form<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ff3662d\" data-id=\"ff3662d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b247340 elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"b247340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">see our <br>contact information<\/h3><p class=\"elementor-image-box-description\">Do you want to contact us directly? You can find all of our location-specific contact details on the same page. <br>Get in touch, we'll take care of it!<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fea5616 elementor-widget elementor-widget-spacer\" data-id=\"fea5616\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcbffd6 elementor-widget elementor-widget-button\" data-id=\"fcbffd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/euroports.staging.bojaco.com\/en\/yhteystietomme\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact us<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-501230a elementor-hidden-tablet\" data-id=\"501230a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Varustamopalvelut Varustamo-palvelut Varustamopalveluita saat meilt\u00e4 ymp\u00e4ri vuorokauden, sill\u00e4 laivanselvitt\u00e4j\u00e4mme ovat tavoitettavissa 24\/7. Edustamme yli 40 eri varustamoa ja selvityksess\u00e4mme on vuosittain yli 1 000 alusta. Palvelumme Hinnasto Yhteystietomme Palveluksessasi 24\/7 Laivanselvitt\u00e4j\u00e4mme ovat palveluksessanne 24\/7. Toimintamme perustuu asiakkaiden tarpeisiin. Huolehdimme kaikesta laivak\u00e4ynnin yhteydenpidosta: luotsin tilaamisesta, laituripaikan varaamisesta, tullauksesta ja lastidokumentoinnista. Laaja kokemuksemme linja- ja muusta laivaliikenteest\u00e4 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-265","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Varustamopalvelut - Euroports Finland<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Varustamopalvelut - Euroports Finland\" \/>\n<meta property=\"og:description\" content=\"Varustamopalvelut Varustamo-palvelut Varustamopalveluita saat meilt\u00e4 ymp\u00e4ri vuorokauden, sill\u00e4 laivanselvitt\u00e4j\u00e4mme ovat tavoitettavissa 24\/7. Edustamme yli 40 eri varustamoa ja selvityksess\u00e4mme on vuosittain yli 1 000 alusta. Palvelumme Hinnasto Yhteystietomme Palveluksessasi 24\/7 Laivanselvitt\u00e4j\u00e4mme ovat palveluksessanne 24\/7. Toimintamme perustuu asiakkaiden tarpeisiin. Huolehdimme kaikesta laivak\u00e4ynnin yhteydenpidosta: luotsin tilaamisesta, laituripaikan varaamisesta, tullauksesta ja lastidokumentoinnista. Laaja kokemuksemme linja- ja muusta laivaliikenteest\u00e4 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/euroports.staging.bojaco.com\/en\/varustamopalvelut\/\" \/>\n<meta property=\"og:site_name\" content=\"Euroports Finland\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-29T12:01:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/euroports.staging.bojaco.com\/wp-content\/uploads\/elementor\/thumbs\/EUROPORTS_finland_Satama_maailmalla-qvvox3fxvh9olk1jv47dyhx6yx7uynvs7iha7ywo3k.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/varustamopalvelut\\\/\",\"url\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/varustamopalvelut\\\/\",\"name\":\"Varustamopalvelut - Euroports Finland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/varustamopalvelut\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/varustamopalvelut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/EUROPORTS_finland_Satama_maailmalla-qvvox3fxvh9olk1jv47dyhx6yx7uynvs7iha7ywo3k.jpg\",\"datePublished\":\"2022-01-09T16:02:52+00:00\",\"dateModified\":\"2025-03-29T12:01:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/varustamopalvelut\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/euroports.staging.bojaco.com\\\/varustamopalvelut\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/varustamopalvelut\\\/#primaryimage\",\"url\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/EUROPORTS_finland_Satama_maailmalla-qvvox3fxvh9olk1jv47dyhx6yx7uynvs7iha7ywo3k.jpg\",\"contentUrl\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/EUROPORTS_finland_Satama_maailmalla-qvvox3fxvh9olk1jv47dyhx6yx7uynvs7iha7ywo3k.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/varustamopalvelut\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Varustamopalvelut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/#website\",\"url\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/\",\"name\":\"Euroports Finland\",\"description\":\"T\u00e4yden palvelun satamaoperaattori.\",\"publisher\":{\"@id\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/#organization\",\"name\":\"Euroports Finland\",\"url\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-euroports_logo.png\",\"contentUrl\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-euroports_logo.png\",\"width\":350,\"height\":100,\"caption\":\"Euroports Finland\"},\"image\":{\"@id\":\"https:\\\/\\\/euroports.staging.bojaco.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Varustamopalvelut - Euroports Finland","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Varustamopalvelut - Euroports Finland","og_description":"Varustamopalvelut Varustamo-palvelut Varustamopalveluita saat meilt\u00e4 ymp\u00e4ri vuorokauden, sill\u00e4 laivanselvitt\u00e4j\u00e4mme ovat tavoitettavissa 24\/7. Edustamme yli 40 eri varustamoa ja selvityksess\u00e4mme on vuosittain yli 1 000 alusta. Palvelumme Hinnasto Yhteystietomme Palveluksessasi 24\/7 Laivanselvitt\u00e4j\u00e4mme ovat palveluksessanne 24\/7. Toimintamme perustuu asiakkaiden tarpeisiin. Huolehdimme kaikesta laivak\u00e4ynnin yhteydenpidosta: luotsin tilaamisesta, laituripaikan varaamisesta, tullauksesta ja lastidokumentoinnista. Laaja kokemuksemme linja- ja muusta laivaliikenteest\u00e4 [&hellip;]","og_url":"https:\/\/euroports.staging.bojaco.com\/en\/varustamopalvelut\/","og_site_name":"Euroports Finland","article_modified_time":"2025-03-29T12:01:16+00:00","og_image":[{"url":"https:\/\/euroports.staging.bojaco.com\/wp-content\/uploads\/elementor\/thumbs\/EUROPORTS_finland_Satama_maailmalla-qvvox3fxvh9olk1jv47dyhx6yx7uynvs7iha7ywo3k.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/euroports.staging.bojaco.com\/varustamopalvelut\/","url":"https:\/\/euroports.staging.bojaco.com\/varustamopalvelut\/","name":"Varustamopalvelut - Euroports Finland","isPartOf":{"@id":"https:\/\/euroports.staging.bojaco.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/euroports.staging.bojaco.com\/varustamopalvelut\/#primaryimage"},"image":{"@id":"https:\/\/euroports.staging.bojaco.com\/varustamopalvelut\/#primaryimage"},"thumbnailUrl":"https:\/\/euroports.staging.bojaco.com\/wp-content\/uploads\/elementor\/thumbs\/EUROPORTS_finland_Satama_maailmalla-qvvox3fxvh9olk1jv47dyhx6yx7uynvs7iha7ywo3k.jpg","datePublished":"2022-01-09T16:02:52+00:00","dateModified":"2025-03-29T12:01:16+00:00","breadcrumb":{"@id":"https:\/\/euroports.staging.bojaco.com\/varustamopalvelut\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/euroports.staging.bojaco.com\/varustamopalvelut\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euroports.staging.bojaco.com\/varustamopalvelut\/#primaryimage","url":"https:\/\/euroports.staging.bojaco.com\/wp-content\/uploads\/elementor\/thumbs\/EUROPORTS_finland_Satama_maailmalla-qvvox3fxvh9olk1jv47dyhx6yx7uynvs7iha7ywo3k.jpg","contentUrl":"https:\/\/euroports.staging.bojaco.com\/wp-content\/uploads\/elementor\/thumbs\/EUROPORTS_finland_Satama_maailmalla-qvvox3fxvh9olk1jv47dyhx6yx7uynvs7iha7ywo3k.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/euroports.staging.bojaco.com\/varustamopalvelut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/euroports.staging.bojaco.com\/"},{"@type":"ListItem","position":2,"name":"Varustamopalvelut"}]},{"@type":"WebSite","@id":"https:\/\/euroports.staging.bojaco.com\/#website","url":"https:\/\/euroports.staging.bojaco.com\/","name":"Euroports Finland","description":"T\u00e4yden palvelun satamaoperaattori.","publisher":{"@id":"https:\/\/euroports.staging.bojaco.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/euroports.staging.bojaco.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/euroports.staging.bojaco.com\/#organization","name":"Euroports Finland","url":"https:\/\/euroports.staging.bojaco.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euroports.staging.bojaco.com\/#\/schema\/logo\/image\/","url":"https:\/\/euroports.staging.bojaco.com\/wp-content\/uploads\/2022\/01\/cropped-euroports_logo.png","contentUrl":"https:\/\/euroports.staging.bojaco.com\/wp-content\/uploads\/2022\/01\/cropped-euroports_logo.png","width":350,"height":100,"caption":"Euroports Finland"},"image":{"@id":"https:\/\/euroports.staging.bojaco.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/euroports.staging.bojaco.com\/en\/wp-json\/wp\/v2\/pages\/265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euroports.staging.bojaco.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/euroports.staging.bojaco.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/euroports.staging.bojaco.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/euroports.staging.bojaco.com\/en\/wp-json\/wp\/v2\/comments?post=265"}],"version-history":[{"count":271,"href":"https:\/\/euroports.staging.bojaco.com\/en\/wp-json\/wp\/v2\/pages\/265\/revisions"}],"predecessor-version":[{"id":12333,"href":"https:\/\/euroports.staging.bojaco.com\/en\/wp-json\/wp\/v2\/pages\/265\/revisions\/12333"}],"wp:attachment":[{"href":"https:\/\/euroports.staging.bojaco.com\/en\/wp-json\/wp\/v2\/media?parent=265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}